{"id":8052,"date":"2018-04-25T21:00:01","date_gmt":"2018-04-25T21:00:01","guid":{"rendered":"http:\/\/solwangdesign.dk\/produkter\/uncategorized\/light-dusty-green-knitted-kitchen-towels\/"},"modified":"2026-05-06T12:40:32","modified_gmt":"2026-05-06T10:40:32","slug":"light-dusty-green-knitted-kitchen-towels","status":"publish","type":"product","link":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/","title":{"rendered":"Light dusty green"},"content":{"rendered":"<p>1 pcs. of knitted kitchen towel in light dusty green.<\/p>\n<p>Tied beautifully with ribbon and brand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kitchen towel in garter stitch<br \/>\nto optimize absorption and functionality.<\/p>\n<p>Size: 32 x 47 cm.<\/p>\n<p>100% Oeko-tex cotton.<br \/>\nWashable at 60 degrees.<\/p>\n<p>Recommendation by the<br \/>\nNational Board of Health.<\/p>\n","protected":false},"featured_media":78027,"template":"","meta":{"_acf_changed":false,"footnotes":""},"product_brand":[],"product_cat":[85],"product_tag":[],"class_list":{"0":"post-8052","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kitchen-towels","7":"pa_color-green","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Light dusty green - Solwang Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Light dusty green - Solwang Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/","url":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/","name":"Light dusty green - Solwang Design","isPartOf":{"@id":"https:\/\/solwangdesign.dk\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/#primaryimage"},"image":{"@id":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/#primaryimage"},"thumbnailUrl":"https:\/\/solwangdesign.dk\/wp-content\/uploads\/2024\/12\/H44.jpg","datePublished":"2018-04-25T21:00:01+00:00","dateModified":"2026-05-06T10:40:32+00:00","breadcrumb":{"@id":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/#primaryimage","url":"https:\/\/solwangdesign.dk\/wp-content\/uploads\/2024\/12\/H44.jpg","contentUrl":"https:\/\/solwangdesign.dk\/wp-content\/uploads\/2024\/12\/H44.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/solwangdesign.dk\/en\/vare\/light-dusty-green-knitted-kitchen-towels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solwangdesign.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/solwangdesign.dk\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Light dusty green"}]},{"@type":"WebSite","@id":"https:\/\/solwangdesign.dk\/en\/#website","url":"https:\/\/solwangdesign.dk\/en\/","name":"Solwang Design","description":"Solwang Design","publisher":{"@id":"https:\/\/solwangdesign.dk\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solwangdesign.dk\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solwangdesign.dk\/en\/#organization","name":"Solwang Design","url":"https:\/\/solwangdesign.dk\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solwangdesign.dk\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solwangdesign.dk\/wp-content\/uploads\/2017\/11\/logo.png","contentUrl":"https:\/\/solwangdesign.dk\/wp-content\/uploads\/2017\/11\/logo.png","width":226,"height":111,"caption":"Solwang Design"},"image":{"@id":"https:\/\/solwangdesign.dk\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solwangdesign","https:\/\/www.instagram.com\/solwangdesign\/"]}]}},"_links":{"self":[{"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/product\/8052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/product\/8052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/media\/78027"}],"wp:attachment":[{"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/media?parent=8052"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/product_brand?post=8052"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/product_cat?post=8052"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/solwangdesign.dk\/en\/wp-json\/wp\/v2\/product_tag?post=8052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}